{"id":49694,"date":"2022-12-29T00:00:00","date_gmt":"2022-12-28T23:00:00","guid":{"rendered":"https:\/\/biorius.com\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/"},"modified":"2024-05-08T11:46:31","modified_gmt":"2024-05-08T09:46:31","slug":"requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito","status":"publish","type":"post","link":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/","title":{"rendered":"Requisiti di etichettatura dei cosmetici nell&#8217;UE e nel Regno Unito"},"content":{"rendered":"\n<p>I requisiti per l&#8217;etichettatura dei cosmetici sono piuttosto complicati e in Europa lo sono ancora di pi\u00f9! \u00c8 un&#8217;ottima idea iniziare a vendere i tuoi prodotti cosmetici nell&#8217;UE e nel Regno Unito perch\u00e9 questi mercati sono, insieme agli Stati Uniti, i pi\u00f9 grandi mercati di prodotti cosmetici al mondo (con un valore di 80 miliardi di euro al prezzo di vendita al dettaglio nel 2021). I <a href=\"https:\/\/cosmeticseurope.eu\/cosmetics-industry\/\">maggiori mercati nazionali di cosmetici e prodotti per la cura della persona in Europa sono<\/a>: Germania (13,6 miliardi di euro), Francia (12,0 miliardi di euro), Italia (10,6 miliardi di euro), Regno Unito (9,9 miliardi di euro), Spagna (6,9 miliardi di euro) e Polonia (4,0 miliardi di euro).<\/p>\n\n<p><\/p>\n\n<h2 class=\"wp-block-heading\">Requisiti per l&#8217;etichettatura dei prodotti cosmetici<\/h2>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"799\" height=\"547\" src=\"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.png\" alt=\"\" class=\"wp-image-26756 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Fai attenzione perch\u00e9 i requisiti di etichettatura dei prodotti cosmetici in Europa sono davvero una questione delicata e le etichette solo in inglese non sono sempre sufficienti. Le etichette (o alcune parti delle etichette) devono essere tradotte nella lingua del paese, ma dipende da ciascun paese dell&#8217;UE&#8230; Biorius, il tuo esperto di regolamentazione dei cosmetici, pu\u00f2 fornirti indicazioni e organizzare le traduzioni per te come parte di un servizio aggiuntivo.<\/p>\n<\/div><\/div>\n\n<p>I rischi associati al mancato rispetto di questo principio dipendono dal paese in cui vengono effettuati i controlli. Ad esempio, per l&#8217;Italia \u00e8 necessario seguire il DECRETO LEGISLATIVO 4 dicembre 2015, n. 204 Disciplina sanzionatoria per la violazione del Regolamento (CE) n. 1223\/2009 sui prodotti cosmetici. L&#8217;art. 5 del presente decreto riporta: Violazione degli obblighi derivanti dall&#8217;articolo 6 del regolamento sugli obblighi dei distributori. Il distributore che non effettua le verifiche di cui all&#8217;articolo 6, paragrafo 2, del regolamento (che includono l&#8217;etichettatura di cui stiamo parlando) \u00e8 punibile con una multa da 3.000\u20ac a 30.000\u20ac.  <\/p>\n\n<h2 class=\"wp-block-heading\">Requisiti per l&#8217;etichettatura dei cosmetici: benvenuti nell&#8217;UE e nei suoi 27 paesi e 24 lingue<\/h2>\n\n<p>L&#8217;UE \u00e8 uno dei mercati pi\u00f9 grandi al mondo per i prodotti cosmetici! Per aiutare i consumatori nei loro acquisti e per proteggere la loro salute, tutte le informazioni importanti devono sempre essere facilmente accessibili, leggibili e comprensibili dal consumatore al momento dell&#8217;acquisto.  <\/p>\n\n<p>Per evitare questi complessi e fastidiosi requisiti di etichettatura dei cosmetici (e le lunghe traduzioni delle etichette in varie lingue), pu\u00f2 sembrare allettante iniziare con il Regno Unito, l&#8217;ottava industria cosmetica pi\u00f9 grande del mondo&#8230; ma questo non ti dar\u00e0 accesso agli altri paesi dell&#8217;UE, ad esempio.<\/p>\n\n<h3 class=\"wp-block-heading\">I requisiti per l&#8217;etichettatura dei cosmetici sono in realt\u00e0 piuttosto semplici<\/h3>\n\n<p>Il consumatore finale deve capire esattamente cosa sta acquistando quando controlla il prodotto.<\/p>\n\n<h2 class=\"wp-block-heading\">Breve promemoria dei requisiti di etichettatura dei cosmetici in Europa<\/h2>\n\n<p>Le norme UE sull&#8217;etichettatura dei cosmetici possono sembrare molto confuse e, sebbene rientrino nella responsabilit\u00e0 dei distributori (secondo l&#8217;articolo 6 del Regolamento UE sui cosmetici), la progettazione e l&#8217;edizione di etichette e confezioni sono e rimangono un esercizio costoso per i proprietari di marchi cosmetici.<\/p>\n\n<p>Alcuni elementi dovranno essere tradotti in tutte le lingue ufficiali dei paesi in cui i prodotti sono commercializzati e i distributori devono assicurarsi che queste informazioni siano tradotte correttamente.<\/p>\n\n<p>I distributori hanno ovviamente il pieno diritto di rifiutare i prodotti non conformi a questi requisiti.<\/p>\n\n<h2 class=\"wp-block-heading\">Requisiti legali minimi imposti dal Regolamento europeo sui cosmetici<\/h2>\n\n<p><a href=\"https:\/\/lexparency.org\/eu\/32009R1223\/ART_19\/\">Secondo l&#8217;articolo 19 \u00a75 del Regolamento UE sui cosmetici<\/a><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Il contenuto nominale<\/li>\n\n\n\n<li>Si utilizza il PaO<strong>(Period<\/strong> <strong>after<\/strong> <strong>Opening<\/strong>) o la data di durata minima (o la data di scadenza dei cosmetici), con frasi del tipo &#8220;Da utilizzare preferibilmente entro il&#8230;&#8221;.<\/li>\n\n\n\n<li>Le avvertenze e i consigli di prudenza<\/li>\n\n\n\n<li>La funzione del prodotto cosmetico (non obbligatoria se ovvia ma da tradurre se riportata sull&#8217;etichetta del prodotto)<\/li>\n\n\n\n<li>Il foglietto illustrativo, l&#8217;etichetta, il nastro adesivo, il cartellino o la scheda allegati, se presenti.<\/li>\n\n\n\n<li>L&#8217;avviso \u00e8 posto nelle immediate vicinanze del contenitore in cui il prodotto cosmetico \u00e8 esposto per la vendita, se presente.<\/li>\n<\/ul>\n\n<p>L&#8217;etichettatura della funzione del prodotto non \u00e8 obbligatoria se questa risulta chiara dalla presentazione del prodotto. Tuttavia, se devi (o decidi di) etichettarlo, allora deve essere nella lingua o nelle lingue appropriate.<\/p>\n\n<p>La traduzione delle indicazioni non \u00e8 un requisito formale della legislazione europea, ma piuttosto un&#8217;interpretazione della legislazione da parte delle autorit\u00e0 nazionali. In effetti, il Regolamento UE n. 655\/2013 sulla giustificazione delle indicazioni cosmetiche indica che  <em>&#8220;L&#8217;accettabilit\u00e0 di un&#8217;indicazione si basa sulla percezione dell&#8217;utente finale medio di un prodotto cosmetico, ragionevolmente informato e ragionevolmente attento e avveduto, tenendo conto dei <strong>fattori<\/strong> sociali, culturali e <strong>linguistici<\/strong> del mercato in questione.&#8221;<\/em><\/p>\n\n<p>Per questo motivo, di solito si ritiene pi\u00f9 sicuro tradurre le indicazioni nella lingua o nelle lingue dei paesi in cui il prodotto viene venduto.<\/p>\n\n<h2 class=\"wp-block-heading\">Traduzioni di etichette cosmetiche<\/h2>\n\n<p>La mancata traduzione delle indicazioni non dovrebbe essere un problema nei paesi del Nord Europa, come ad esempio Paesi Bassi, Finlandia, Danimarca, Svezia o Islanda, ma \u00e8 probabile che lo sia nei paesi dell&#8217;Europa meridionale.<\/p>\n\n<p>Un paese che ha addirittura approvato una legge nazionale per garantire che tutto ci\u00f2 che \u00e8 riportato sull&#8217;etichetta sia tradotto nella lingua nazionale \u00e8 la Francia. Non tradurre le etichette in francese se i prodotti vengono immessi in questi mercati pu\u00f2 comportare problemi di conformit\u00e0.<\/p>\n\n<p>In Francia, infatti, la legge di Toulon (n\u00b094-665 del 4 agosto 1994) ti obbliga a utilizzare la lingua francese per l&#8217;etichettatura. L&#8217;unico elemento dell&#8217;etichetta che \u00e8 esente da traduzione \u00e8 la dicitura &#8220;Made in&#8221;. Questa esenzione non si estende a dichiarazioni simili come &#8220;Paese d&#8217;origine&#8221;.<\/p>\n\n<p>Un altro esempio \u00e8 l&#8217;Italia, dove le dogane effettuano controlli scrupolosi per assicurarsi che i prodotti riportino correttamente la lingua italiana.<\/p>\n\n<h2 class=\"wp-block-heading\">Riepilogo dei requisiti per l&#8217;etichettatura dei cosmetici<\/h2>\n\n<p>Una revisione delle etichette in Europa (revisione completa e revisione delle etichette e dei claim che tenga conto di tutte le normative europee) e una consulenza su claim o argomenti specifici che il marchio vuole promuovere come testo di marketing da parte di un&#8217;azienda riconosciuta e rinomata (come Biorius) sembrano davvero l&#8217;idea migliore per la tua attivit\u00e0.<\/p>\n\n<h2 class=\"wp-block-heading\">E infine, ma non meno importante, la Persona Responsabile (o il Rappresentante Legale)<\/h2>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/representative-2-1024x683-1.jpg\" alt=\"\" class=\"wp-image-24764 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Anche la Persona Responsabile deve comparire sulle etichette (si tratta di un obbligo di legge assolutamente obbligatorio).<\/p>\n\n\n\n<p>La Persona Responsabile (o il Rappresentante Legale) deve essere facilmente reperibile e contattabile per i seguenti motivi:<\/p>\n<\/div><\/div>\n\n<ul class=\"wp-block-list\">\n<li>Proteggere un marchio dai problemi di conformit\u00e0<\/li>\n\n\n\n<li>Assistenza per le questioni legali relative al regolamento UE sui cosmetici.<\/li>\n\n\n\n<li>Rispondere a tutte le domande delle autorit\u00e0 nazionali competenti (27 Stati membri dell&#8217;UE)<\/li>\n\n\n\n<li>Gestire tutte le ispezioni decise dalle autorit\u00e0 di vigilanza competenti.<\/li>\n\n\n\n<li>Tenere d&#8217;occhio gli sviluppi normativi e mantenere un marchio aggiornato<\/li>\n\n\n\n<li>Gestire tutti i problemi di cosmetovigilanza (effetti indesiderati) seguendo i consumatori e assicurando il miglior corso d&#8217;azione<\/li>\n<\/ul>\n\n<p>Le notifiche del CPNP sono sempre effettuate dalla Persona Responsabile (o dal Rappresentante Legale).<\/p>\n\n<h2 class=\"wp-block-heading\">Significato di CPNP<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>CPNP = <strong>Portale di<\/strong> <strong>notifica<\/strong>dei <strong>prodotti<\/strong> <strong>cosmetici<\/strong><\/li>\n\n\n\n<li>Il CPNP \u00e8 una notifica all&#8217;Europa che un prodotto cosmetico sar\u00e0 venduto in Europa.<\/li>\n\n\n\n<li>Le notifiche del CPNP vengono fatte in modo che le autorit\u00e0 nazionali competenti europee sappiano chi devono contattare se vogliono organizzare un&#8217;ulteriore ispezione.<\/li>\n<\/ul>\n\n<p>Concludo queste spiegazioni dicendo che Biorius pu\u00f2 ovviamente aiutarti in tutti i punti sopra elencati. Non esitare a contattarci.<\/p>\n\n<h2 class=\"wp-block-heading\">Contattaci<\/h2>\n\n<p>Per maggiori informazioni, non esitare a contattare il tuo CRM<strong>(Customer<\/strong> <strong>Relationship<\/strong> <strong>Manager<\/strong>), se sei gi\u00e0 cliente Biorius, o a contattarci all&#8217;indirizzo <a href=\"mailto:info@biorius.com\">info@biorius.com.<\/a><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I requisiti per l&#8217;etichettatura dei cosmetici sono piuttosto complicati e in Europa lo sono ancora di pi\u00f9! \u00c8 un&#8217;ottima idea iniziare a vendere i tuoi&#8230;<\/p>\n","protected":false},"author":2,"featured_media":43409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[2291],"tags":[],"ppma_author":[],"class_list":["post-49694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regolamenti-cosmetici"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Requisiti di etichettatura dei cosmetici nell&#039;UE e nel Regno Unito - Biorius<\/title>\n<meta name=\"description\" content=\"I requisiti per l&#039;etichettatura dei cosmetici sono piuttosto complicati (e lo sono ancora di pi\u00f9 in Europa) e Biorius pu\u00f2 aiutarti completamente in questa materia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Requisiti di etichettatura dei cosmetici nell&#039;UE e nel Regno Unito - Biorius\" \/>\n<meta property=\"og:description\" content=\"I requisiti per l&#039;etichettatura dei cosmetici sono piuttosto complicati (e lo sono ancora di pi\u00f9 in Europa) e Biorius pu\u00f2 aiutarti completamente in questa materia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/\" \/>\n<meta property=\"og:site_name\" content=\"Biorius\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T09:46:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.png\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"547\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nicolas.lenaers@biorius.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nicolas.lenaers@biorius.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/\"},\"author\":{\"name\":\"nicolas.lenaers@biorius.com\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\"},\"headline\":\"Requisiti di etichettatura dei cosmetici nell&#8217;UE e nel Regno Unito\",\"datePublished\":\"2022-12-28T23:00:00+00:00\",\"dateModified\":\"2024-05-08T09:46:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/\"},\"wordCount\":1197,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/eu-uk.webp\",\"articleSection\":[\"Regolamenti Cosmetici\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/\",\"url\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/\",\"name\":\"Requisiti di etichettatura dei cosmetici nell'UE e nel Regno Unito - Biorius\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/eu-uk.webp\",\"datePublished\":\"2022-12-28T23:00:00+00:00\",\"dateModified\":\"2024-05-08T09:46:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\"},\"description\":\"I requisiti per l'etichettatura dei cosmetici sono piuttosto complicati (e lo sono ancora di pi\u00f9 in Europa) e Biorius pu\u00f2 aiutarti completamente in questa materia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/eu-uk.webp\",\"contentUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/eu-uk.webp\",\"width\":799,\"height\":547},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/cosmetic-news\\\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/biorius.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Requisiti di etichettatura dei cosmetici nell&#8217;UE e nel Regno Unito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/biorius.com\\\/it\\\/\",\"name\":\"Biorius\",\"description\":\"You create dreams we protect them\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biorius.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biorius.com\\\/it\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\",\"name\":\"nicolas.lenaers@biorius.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=gf65cae9e2e07fb542ca434cf6ec306ac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g\",\"caption\":\"nicolas.lenaers@biorius.com\"},\"url\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/author\\\/nicolas-lenaersbiorius-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Requisiti di etichettatura dei cosmetici nell'UE e nel Regno Unito - Biorius","description":"I requisiti per l'etichettatura dei cosmetici sono piuttosto complicati (e lo sono ancora di pi\u00f9 in Europa) e Biorius pu\u00f2 aiutarti completamente in questa materia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/","og_locale":"it_IT","og_type":"article","og_title":"Requisiti di etichettatura dei cosmetici nell'UE e nel Regno Unito - Biorius","og_description":"I requisiti per l'etichettatura dei cosmetici sono piuttosto complicati (e lo sono ancora di pi\u00f9 in Europa) e Biorius pu\u00f2 aiutarti completamente in questa materia.","og_url":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/","og_site_name":"Biorius","article_published_time":"2022-12-28T23:00:00+00:00","article_modified_time":"2024-05-08T09:46:31+00:00","og_image":[{"width":799,"height":547,"url":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.png","type":"image\/png"}],"author":"nicolas.lenaers@biorius.com","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"nicolas.lenaers@biorius.com","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#article","isPartOf":{"@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/"},"author":{"name":"nicolas.lenaers@biorius.com","@id":"https:\/\/biorius.com\/it\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3"},"headline":"Requisiti di etichettatura dei cosmetici nell&#8217;UE e nel Regno Unito","datePublished":"2022-12-28T23:00:00+00:00","dateModified":"2024-05-08T09:46:31+00:00","mainEntityOfPage":{"@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/"},"wordCount":1197,"commentCount":0,"image":{"@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#primaryimage"},"thumbnailUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.webp","articleSection":["Regolamenti Cosmetici"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/","url":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/","name":"Requisiti di etichettatura dei cosmetici nell'UE e nel Regno Unito - Biorius","isPartOf":{"@id":"https:\/\/biorius.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#primaryimage"},"image":{"@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#primaryimage"},"thumbnailUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.webp","datePublished":"2022-12-28T23:00:00+00:00","dateModified":"2024-05-08T09:46:31+00:00","author":{"@id":"https:\/\/biorius.com\/it\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3"},"description":"I requisiti per l'etichettatura dei cosmetici sono piuttosto complicati (e lo sono ancora di pi\u00f9 in Europa) e Biorius pu\u00f2 aiutarti completamente in questa materia.","breadcrumb":{"@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#primaryimage","url":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.webp","contentUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/eu-uk.webp","width":799,"height":547},{"@type":"BreadcrumbList","@id":"https:\/\/biorius.com\/it\/cosmetic-news\/requisiti-di-etichettatura-dei-cosmetici-nellue-e-nel-regno-unito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/biorius.com\/it\/"},{"@type":"ListItem","position":2,"name":"Requisiti di etichettatura dei cosmetici nell&#8217;UE e nel Regno Unito"}]},{"@type":"WebSite","@id":"https:\/\/biorius.com\/it\/#website","url":"https:\/\/biorius.com\/it\/","name":"Biorius","description":"You create dreams we protect them","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biorius.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/biorius.com\/it\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3","name":"nicolas.lenaers@biorius.com","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=gf65cae9e2e07fb542ca434cf6ec306ac","url":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","caption":"nicolas.lenaers@biorius.com"},"url":"https:\/\/biorius.com\/fr\/cosmetic-news\/author\/nicolas-lenaersbiorius-com\/"}]}},"authors":[{"term_id":2594,"user_id":2,"is_guest":0,"slug":"nicolas-lenaersbiorius-com","display_name":"nicolas.lenaers@biorius.com","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/posts\/49694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/comments?post=49694"}],"version-history":[{"count":0,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/posts\/49694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/media\/43409"}],"wp:attachment":[{"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/media?parent=49694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/categories?post=49694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/tags?post=49694"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/biorius.com\/it\/wp-json\/wp\/v2\/ppma_author?post=49694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}