{"id":49220,"date":"2019-12-13T00:00:00","date_gmt":"2019-12-12T23:00:00","guid":{"rendered":"https:\/\/biorius.com\/cosmetic-news\/le-reglement-omnibus\/"},"modified":"2025-01-13T09:59:55","modified_gmt":"2025-01-13T08:59:55","slug":"le-reglement-omnibus","status":"publish","type":"post","link":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/","title":{"rendered":"R\u00e8glement Omnibus 2019"},"content":{"rendered":"&#13;\n<h2 class=\"wp-block-heading\">R\u00e8glement Omnibus 2019 : Mise \u00e0 jour<\/h2>&#13;\n&#13;\n<p><em><span class=\"ugb-highlight\" style=\"color: #93d500;\"><sup>13<\/sup> d\u00e9cembre 2019<\/span><\/em><\/p>&#13;\n&#13;\n<p>Comme estim\u00e9 ci-dessous, le R\u00e8glement Omnibus 2019 a \u00e9t\u00e9 publi\u00e9 et nous vous invitons \u00e0 consulter le texte l\u00e9gal <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/?uri=uriserv:OJ.L_.2019.307.01.0015.01.ENG&amp;toc=OJ:L:2019:307:TOC\">EU No 2019\/1966<\/a>. Le principal (voire unique) impact de ce nouveau r\u00e8glement sur l&#8217;industrie cosm\u00e9tique concerne l&#8217;utilisation de l&#8217;acide salicylique et de ses sels.<\/p>&#13;\n&#13;\n<p>En outre, la p\u00e9riode de transition indiqu\u00e9e dans le projet de r\u00e8glement a \u00e9t\u00e9 confirm\u00e9e. Les nouvelles exigences l\u00e9gales relatives \u00e0 l&#8217;acide salicylique et \u00e0 ses sels entreront en vigueur le<sup>1er<\/sup> mai 2020.<\/p>&#13;\n\n<div id=\"\" class=\"wp-block-ugb-cta ugb-cta ugb-74ae645 ugb-cta ugb-cta--v2 ugb-cta--design-plain ugb-main-block\"><style>.ugb-74ae645 .ugb-button .ugb-button--inner{color:#93D500 !important}.ugb-74ae645 .ugb-button{border-color:#93D500 !important}.ugb-74ae645 .ugb-button:hover .ugb-button--inner{color:#93D500 !important}<\/style>\n<div class=\"ugb-inner-block\">\n<div class=\"ugb-block-content\">\n<div class=\"ugb-cta__item\">\n<h3 class=\"ugb-cta__title\">Des questions ?<\/h3>\n<div class=\"ugb-button-container\"><a class=\"ugb-button ugb-button--size-normal ugb-button--design-ghost\" href=\"https:\/\/biorius.com\/fr\/contact\/\" rel=\"\"><span class=\"ugb-button--inner\">Contactez nous<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n&#13;\n<h2 class=\"wp-block-heading\"><strong>Attention : Acide salicylique<\/strong><\/h2>&#13;\n&#13;\n<p><em><span class=\"ugb-highlight\" style=\"color: #93d500;\"><sup>11<\/sup> juillet 2019<\/span><\/em><br\/><br\/>Peu apr\u00e8s la publication du &#8220;R\u00e8glement Omnibus 2018&#8221; (voir IL-061), la Commission europ\u00e9enne a lanc\u00e9 une consultation publique concernant la prochaine version du &#8220;R\u00e8glement Omnibus 2019&#8221;. D\u00e9sormais, une telle modification du r\u00e8glement europ\u00e9en sur les cosm\u00e9tiques, interdisant les lots de substances class\u00e9es CMR, sera publi\u00e9e chaque ann\u00e9e.<br\/><br\/>Comme vous le savez peut-\u00eatre, l&#8217;article 15 du r\u00e8glement europ\u00e9en sur les cosm\u00e9tiques r\u00e9git l&#8217;utilisation des substances CMR dans les produits cosm\u00e9tiques. En principe, l&#8217;utilisation des substances CMR est interdite dans l&#8217;UE, bien que des d\u00e9rogations restent possibles dans des conditions sp\u00e9cifiques. La proc\u00e9dure r\u00e9glementaire implique la publication d&#8217;une modification de l&#8217;annexe II (substances interdites) avant que l&#8217;interdiction ne prenne effet. L&#8217;annexe III (substances r\u00e9glement\u00e9es) et l&#8217;annexe V (agents conservateurs) peuvent \u00e9galement devoir \u00eatre adapt\u00e9es si une d\u00e9rogation est accord\u00e9e.<br\/><br\/>Le<a href=\"https:\/\/ec.europa.eu\/growth\/tools-databases\/tbt\/en\/search\/?tbtaction=search.detail&amp;Country_ID=EU&amp;num=666&amp;dspLang=en&amp;basdatedeb=&amp;basdatefin=&amp;baspays=&amp;basnotifnum=&amp;basnotifnum2=&amp;bastypepays=CE&amp;baskeywords=\"> projet de &#8220;R\u00e8glement Omnibus 2019&#8221; est actuellement en consultation<\/a> au niveau de l&#8217;Organisation mondiale du commerce et ce jusqu&#8217;au 11 ao\u00fbt 2019. Le nouveau r\u00e8glement devrait \u00eatre publi\u00e9 d&#8217;ici la fin de l&#8217;ann\u00e9e et sans autres modifications. Le contenu de ce r\u00e8glement est pr\u00e9sent\u00e9 ci-dessous. Malgr\u00e9 une longue liste d&#8217;ingr\u00e9dients, seuls quelques-uns sont pertinents pour l&#8217;industrie cosm\u00e9tique :<\/p>&#13;\n&#13;\n<p><strong>Ingr\u00e9dients cosm\u00e9tiques interdits (ajout \u00e0 l&#8217;annexe II) :<\/strong><\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Nom<\/span><\/em><\/strong><\/td>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Entr\u00e9e pr\u00e9c\u00e9dente<\/span><\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Ac\u00e9tald\u00e9hyde ; Ethanal<\/td>&#13;\n<td>\/<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Quinolin-8-ol (INCI : Oxyquinoline, CAS 148-24-3)<\/td>&#13;\n<td>III.51<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>4-M\u00e9thyl-o-ph\u00e9nyl\u00e8nediamine ; 3,4-Diaminotolu\u00e8ne (INCI : Diaminotolu\u00e8ne)<\/td>&#13;\n<td>III.9<\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<p><strong><span class=\"ugb-highlight\" style=\"color: #000;\">Restrictions suppl\u00e9mentaires applicables aux ingr\u00e9dients cosm\u00e9tiques (modification de l&#8217;annexe III et de l&#8217;annexe V) :<\/span><\/strong><\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Nom<\/span><\/em><\/strong><\/td>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Entr\u00e9e<\/span><\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Acide salicylique utilis\u00e9 \u00e0 d&#8217;autres fins que la conservation<\/td>&#13;\n<td>III.98<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Acide salicylique et ses sels utilis\u00e9s comme conservateur<\/td>&#13;\n<td>V.3<\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<p>Si l&#8217;interdiction des trois premiers ingr\u00e9dients ne devrait avoir que tr\u00e8s peu d&#8217;impact (voire aucun), nous vous demandons d&#8217;accorder la plus grande attention aux nouvelles restrictions concernant l&#8217;acide salicylique et ses sels.<\/p>&#13;\n&#13;\n<p>Acide salicylique et ses sels<span class=\"ugb-highlight\" style=\"color: #93d500;\">\n  <strong>\n    <em>*<\/em>\n  <\/strong>\n<\/span> ont \u00e9t\u00e9 r\u00e9cemment class\u00e9s comme substances toxiques pour la reproduction. Cependant, le Comit\u00e9 scientifique pour la s\u00e9curit\u00e9 des consommateurs a publi\u00e9 un avis scientifique positif le 21 d\u00e9cembre 2018 (avec un corrigendum le 21 juin 2019), qui soutient l&#8217;utilisation en toute s\u00e9curit\u00e9 de l&#8217;acide salicylique dans des conditions sp\u00e9cifiques. Les conclusions du CSSC ont \u00e9t\u00e9 transpos\u00e9es dans le projet de l\u00e9gislation actuel :<\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Cat\u00e9gorie de produit<\/span><\/em><\/strong><\/td>&#13;\n<td><strong><span class=\"ugb-highlight\" style=\"color: #93d500;\"><em>Situation actuelle<\/em><\/span><\/strong><\/td>&#13;\n<td><strong><span class=\"ugb-highlight\" style=\"color: #93d500;\">Situation future<\/span><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Produits destin\u00e9s aux enfants de moins de 3 ans<\/td>&#13;\n<td><strong>Utilisation sans conservateur<\/strong>: Interdit sauf pour les shampooings (max. 3 %)<br\/><strong>Sur l&#8217;\u00e9tiquette<\/strong>: la fonction de l&#8217;ingr\u00e9dient &#8211; par exemple, acide salicylique (antipelliculaire).<\/td>&#13;\n<td><strong>Utilisation sans conservateur<\/strong>: <span class=\"ugb-highlight\" style=\"color: #93d500;\">Interdit<\/span><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td><strong> <\/strong><\/td>&#13;\n<td><strong>Utilisation de conservateurs<\/strong>: Interdit sauf pour les shampooings (max. 0,5 %)<\/td>&#13;\n<td><strong>Utilisation comme conservateur<\/strong>: Interdit <span class=\"ugb-highlight\" style=\"color: #93d500;\">, mais les sels d&#8217;acide salicylique sont autoris\u00e9s \u00e0 hauteur de 0,5 % (en tant qu&#8217;acide) uniquement dans les shampooings<\/span>.<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Produits capillaires \u00e0 rincer<\/td>&#13;\n<td><strong>Utilisation sans conservateur<\/strong>: Maximum 3,0 %<br\/><strong>\u00c9tiqueter<\/strong>: la fonction de l&#8217;ingr\u00e9dient &#8211; par exemple, l&#8217;acide salicylique (antipelliculaire).<\/td>&#13;\n<td><strong>Utilisation sans conservation<\/strong>: Maximum 3,0 %<br\/><strong>\u00c9tiqueter<\/strong>: la fonction de l&#8217;ingr\u00e9dient &#8211; par ex. Acide salicylique (antipelliculaire)<br\/><br\/><span class=\"ugb-highlight\" style=\"color: #93d500;\"><strong>Produits pouvant entra\u00eener une exposition des poumons de l&#8217;utilisateur final par inhalation :<\/strong> Interdit<\/span><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>\u00a0<\/td>&#13;\n<td><strong>Utilisation comme<\/strong><strong>conservateur<\/strong>: Maximum 0,5 % (en tant qu&#8217;acide) d&#8217;acide salicylique ou de ses sels.<\/td>&#13;\n<td><strong>Utilisation comme<\/strong><strong>conservateur<\/strong>: Maximum 0,5 % (en tant qu&#8217;acide) d&#8217;acide salicylique ou de ses sels<br\/><br\/><span class=\"ugb-highlight\" style=\"color: #93d500;\"><strong>Produits pouvant entra\u00eener une exposition des poumons de l&#8217;utilisateur final par inhalation :<\/strong> Interdit<\/span><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>\u00a0<\/td>&#13;\n<td><strong>\u00c9tiqueter (tous types d&#8217;utilisation) :<\/strong><br\/>&#8211; &#8220;Ne pas utiliser pour les enfants de moins de 3 ans&#8221; si :<br\/>&#8211; Le produit peut \u00eatre utilis\u00e9 pour les enfants de moins de 3 ans.<br\/>&#8211; Le produit reste en contact prolong\u00e9 avec la peau.<\/td>&#13;\n<td><strong>\u00c9tiquetage (tous types d&#8217;utilisation)<\/strong>:<br\/>&#8211; &#8220;Ne pas utiliser pour les enfants de moins de 3 ans&#8221; si :<br\/> &#8211; Le produit peut \u00eatre utilis\u00e9 pour les enfants de moins de 3 ans.<br\/> &#8211; Le produit reste en contact prolong\u00e9 avec la peau.<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Autres produits<\/td>&#13;\n<td><strong>Utilisation sans conservateur<\/strong>: Maximum 2,0 %<br\/><strong>\u00c9tiqueter<\/strong>: la fonction de l&#8217;ingr\u00e9dient &#8211; par exemple, l&#8217;acide salicylique (antipelliculaire).<\/td>&#13;\n<td><strong>Utilisation sans conservateur<\/strong>: Maximum 2,0 %<br\/><strong>\u00c9tiqueter<\/strong>: la fonction de l&#8217;ingr\u00e9dient &#8211; par ex. acide salicylique (antipelliculaire)<br\/><br\/><span class=\"ugb-highlight\" style=\"color: #93d500;\"><strong>Produits oraux, lotions corporelles, fards \u00e0 paupi\u00e8res, mascaras, eye-liners, rouges \u00e0 l\u00e8vres, d\u00e9odorants \u00e0 bille et produits susceptibles d&#8217;exposer les poumons de l&#8217;utilisateur final par inhalation :<\/strong> Interdit<\/span><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>\u00a0<\/td>&#13;\n<td><strong>Utilisation comme conservateur<\/strong>: Maximum 0,5 % (en tant qu&#8217;acide) d&#8217;acide salicylique ou de ses sels.<\/td>&#13;\n<td><strong>Utilisation d&#8217;un conservateur<\/strong>: Maximum 0,5 % (en tant qu&#8217;acide) d&#8217;acide salicylique ou de ses sels<br\/><br\/><span class=\"ugb-highlight\" style=\"color: #93d500;\"><strong>Produits oraux et produits pouvant entra\u00eener une exposition des poumons de l&#8217;utilisateur final par inhalation :<\/strong> Interdit (\u00e0 l&#8217;exception des rouges \u00e0 l\u00e8vres)<\/span><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>\u00a0<\/td>&#13;\n<td><strong>\u00c9tiqueter (tous types d&#8217;utilisation) :<\/strong><br\/>&#8211; &#8220;Ne pas utiliser pour les enfants de moins de 3 ans&#8221; si : &#8211;<br\/> Le produit peut \u00eatre utilis\u00e9 pour les enfants de moins de 3 ans.<br\/>&#8211; Le produit reste en contact prolong\u00e9 avec la peau.<\/td>&#13;\n<td><strong>\u00c9tiqueter (tous types d&#8217;utilisation) :<\/strong><br\/>&#8211; &#8220;Ne pas utiliser pour les enfants de moins de 3 ans&#8221; si :<br\/>&#8211; Le produit peut \u00eatre utilis\u00e9 pour les enfants de moins de 3 ans.<br\/>&#8211; Le produit reste en contact prolong\u00e9 avec la peau.<\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<p><em>\n  <u>Produits susceptibles d&#8217;exposer les poumons de l&#8217;utilisateur final par inhalation : <\/u>\n<\/em><em>Ces termes d\u00e9signent g\u00e9n\u00e9ralement des cat\u00e9gories de produits sp\u00e9cifiques, notamment les a\u00e9rosols, certains types de pulv\u00e9risations et les poudres libres (si la taille des particules\/gouttelettes d\u00e9passe 10 microm\u00e8tres).<\/em><\/p>&#13;\n&#13;\n<p>Selon le plan de la Commission europ\u00e9enne, ce r\u00e8glement devrait \u00eatre appliqu\u00e9 d&#8217;ici la fin de l&#8217;ann\u00e9e. Une courte p\u00e9riode de transition sera accord\u00e9e et les changements juridiques mentionn\u00e9s ci-dessus commenceront \u00e0 s&#8217;appliquer le <strong>1 er mai 2020<\/strong>.<\/p>&#13;\n&#13;\n<p><em><strong>\n  <span class=\"ugb-highlight\" style=\"color: #93d500;\">*<\/span>\n<\/strong> Acide salicylique et ses sels<\/em><\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong>INCI<\/strong><\/td>&#13;\n<td><strong>CAS<\/strong><\/td>&#13;\n<td><strong>EINECS<\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Acide salicylique<\/td>&#13;\n<td>69-72-7<\/td>&#13;\n<td>200-712-3<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Salicylate de calcium<\/td>&#13;\n<td>824-35-1<\/td>&#13;\n<td>212-525-4<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Salicylate de magn\u00e9sium<\/td>&#13;\n<td>18917-89-0<\/td>&#13;\n<td>242-669-3<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>MEA- salicylate<\/td>&#13;\n<td>59866- 70-5<\/td>&#13;\n<td>261-963-2<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Salicylate de sodium<\/td>&#13;\n<td>54-21-7<\/td>&#13;\n<td>200-198-0<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Salicylate de potassium<\/td>&#13;\n<td>578-36-9<\/td>&#13;\n<td>209-421-6<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>TEA- salicylate<\/td>&#13;\n<td>2174-16-5<\/td>&#13;\n<td>218-531-3<\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<h2 class=\"wp-block-heading\"><strong>Publication du &#8220;r\u00e8glement omnibus  <\/strong><\/h2>&#13;\n&#13;\n<p><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">27 mai 2019<\/span><\/em><\/p>&#13;\n&#13;\n<p>L&#8217;article 15 du r\u00e8glement europ\u00e9en sur les cosm\u00e9tiques r\u00e9git l&#8217;utilisation des substances CMR dans les produits cosm\u00e9tiques. En principe, l&#8217;utilisation des substances CMR est interdite dans l&#8217;UE, bien que des d\u00e9rogations restent possibles dans des conditions sp\u00e9cifiques. La proc\u00e9dure r\u00e9glementaire implique la publication d&#8217;une modification de l&#8217;annexe II (substances interdites) avant que l&#8217;interdiction ne prenne effet. L&#8217;annexe III (substances r\u00e9glement\u00e9es) et l&#8217;annexe V (agents conservateurs) peuvent \u00e9galement devoir \u00eatre adapt\u00e9es si une d\u00e9rogation est accord\u00e9e.<\/p>&#13;\n&#13;\n<p>Le r\u00e8glement <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/PDF\/?uri=CELEX:32019R0831&amp;qid=1494233068597&amp;from=EN\">UE n\u00b0 2019\/831<\/a> tant attendu (dit &#8220;r\u00e8glement Omnibus&#8221;) a \u00e9t\u00e9 adopt\u00e9 le 22 mai et interdit explicitement l&#8217;utilisation de 227 substances. En outre, elle restreint l&#8217;utilisation de quatre autres. La plupart des substances interdites n&#8217;\u00e9taient de toute fa\u00e7on pas utilis\u00e9es dans les produits cosm\u00e9tiques et sont mentionn\u00e9es dans ce r\u00e8glement afin d&#8217;adapter le r\u00e8glement europ\u00e9en sur les cosm\u00e9tiques aux nouvelles classifications du r\u00e8glement CLP (CE n\u00b0 1272\/2008). Seules les substances mentionn\u00e9es ci-dessous ont une utilisation document\u00e9e dans les produits cosm\u00e9tiques :<\/p>&#13;\n&#13;\n<p><strong>Ingr\u00e9dients cosm\u00e9tiques interdits (ajout \u00e0 l&#8217;annexe II) :<\/strong><\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Nom<\/span><\/em><\/strong><\/td>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Entr\u00e9e pr\u00e9c\u00e9dente<\/span><\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>M\u00e9th\u00e9namine 3-Chloroallylochloride (INCI : Quaternium 15)<\/td>&#13;\n<td>V, 31<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>2-Chlorac\u00e9tamide (INCI : Chloroacetamide)<\/td>&#13;\n<td>V, 41<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Dichlorom\u00e9thane<\/td>&#13;\n<td>III, 7<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Formald\u00e9hyde, paraformald\u00e9hyde et m\u00e9thyl\u00e8ne glycol (aucune d\u00e9rogation accord\u00e9e)<\/td>&#13;\n<td>III, 13 et V, 5<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Acide perborique et perborate de sodium<\/td>&#13;\n<td>III, 1a et III, 12<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Borates, t\u00e9traborates et octaborates et autres sels ou esters de l&#8217;acide borique<\/td>&#13;\n<td>III, 1a et III, 1b<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Cyclotetrasiloxane (D4)<\/td>&#13;\n<td><strong><em>\/<\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Pyrrolidone de m\u00e9thyle<\/td>&#13;\n<td><strong><em>\/<\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<p>La pr\u00e9sence non intentionnelle de cyclotetrasiloxane est tol\u00e9r\u00e9e. En effet, le cyclotetrasiloxane est une impuret\u00e9 courante provenant du processus de fabrication d&#8217;autres silicones tels que le cyclopentasiloxane ou le dim\u00e9thicone. Le niveau de trace \u00e0 ne pas d\u00e9passer peut \u00eatre d\u00e9termin\u00e9 comme suit :<\/p>&#13;\n\r\n<ul class=\"wp-block-list\">&#13;\n<li>Maximum 0,1% dans les produits \u00e0 rincer en raison de la restriction REACH (voir IL-051) limitant la pr\u00e9sence de D4, D5 et D6 dans les produits \u00e0 rincer \u00e0 0,1%, quelles que soient leur source et leur fonction, \u00e0 partir du 31 janvier 2020.<\/li>&#13;\n\r\n\r\n&#13;\n<li>Maximum 0,3 % dans les produits sans rin\u00e7age, car le d\u00e9passement de cette concentration peut difficilement \u00eatre consid\u00e9r\u00e9 comme in\u00e9vitable dans le cadre des bonnes pratiques de fabrication.<\/li>&#13;\n<\/ul>\r\n&#13;\n<p><strong>Restrictions suppl\u00e9mentaires sur les ingr\u00e9dients cosm\u00e9tiques (ajout \u00e0 l&#8217;annexe III) :<\/strong><\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong><span class=\"ugb-highlight\" style=\"color: #93d500;\"><em>Nom<\/em><\/span><\/strong><\/td>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Conditions<\/span><\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>2-Furald\u00e9hyde (Furfural)<\/td>&#13;\n<td>Maximum 10 ppm (0,001 %)<\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Oxyde de diph\u00e9nyl(2,4,6-trim\u00e9thylbenzoyl)phosphine (INCI : Trim\u00e9thylbenzoyl diph\u00e9nylphosphine oxide)<\/td>&#13;\n<td>Maximum 5,0 % dans les produits de modelage des ongles destin\u00e9s aux professionnels (aucune autre utilisation autoris\u00e9e)<\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<p>L&#8217;utilisation de l&#8217;oxyde de trim\u00e9thylbenzoyle diph\u00e9nylphosphine ne sera autoris\u00e9e que pour l&#8217;application de syst\u00e8mes d&#8217;ongles artificiels. Au-del\u00e0 de la limite de concentration, les avertissements suivants devront figurer sur les \u00e9tiquettes des produits :<\/p>&#13;\n\r\n<ul class=\"wp-block-list\">&#13;\n<li>R\u00e9serv\u00e9 \u00e0 un usage professionnel<\/li>&#13;\n\r\n\r\n&#13;\n<li>\u00c9viter le contact avec la peau<\/li>&#13;\n\r\n\r\n&#13;\n<li>Lisez attentivement le mode d&#8217;emploi<\/li>&#13;\n<\/ul>\r\n&#13;\n<p><strong>Ingr\u00e9dients cosm\u00e9tiques soumis \u00e0 des restrictions suppl\u00e9mentaires (ajout \u00e0 l&#8217;annexe V<\/strong>) :<\/p>&#13;\n&#13;\n<figure class=\"wp-block-table\">&#13;\n<table>&#13;\n<tbody>&#13;\n<tr>&#13;\n<td><strong><span class=\"ugb-highlight\" style=\"color: #93d500;\"><em>Nom<\/em><\/span><\/strong><\/td>&#13;\n<td><strong><em><span class=\"ugb-highlight\" style=\"color: #93d500;\">Conditions<\/span><\/em><\/strong><\/td>&#13;\n<\/tr>&#13;\n<tr>&#13;\n<td>Chlorhydrate de polyhexam\u00e9thyl\u00e8ne biguanide (INCI : Polyaminopropyl Biguanide), PHMB<\/td>&#13;\n<td>Maximum 0,1 %.<\/td>&#13;\n<\/tr>&#13;\n<\/tbody>&#13;\n<\/table>&#13;\n<\/figure>&#13;\n&#13;\n<p>Toutefois, l&#8217;utilisation du polyaminopropyl biguanide est interdite dans les applications susceptibles d&#8217;entra\u00eener une exposition des poumons de l&#8217;utilisateur final par inhalation (a\u00e9rosols, pulv\u00e9risations si la taille des gouttelettes est inf\u00e9rieure \u00e0 10 \u00b5M, poudres libres, etc.)<\/p>&#13;\n&#13;\n<p>Ce r\u00e8glement entrera en vigueur le 11 juin 2019. Comme indiqu\u00e9 pr\u00e9c\u00e9demment, <strong>aucune p\u00e9riode de transition ne sera accord\u00e9e<\/strong> et les exigences l\u00e9gales commenceront donc \u00e0 s&#8217;appliquer \u00e0 la date d&#8217;entr\u00e9e en vigueur du r\u00e8glement.<\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; R\u00e8glement Omnibus 2019 : Mise \u00e0 jour&#13; &#13; 13 d\u00e9cembre 2019&#13; &#13; Comme estim\u00e9 ci-dessous, le R\u00e8glement Omnibus 2019 a \u00e9t\u00e9 publi\u00e9 et nous&#8230;<\/p>\n","protected":false},"author":2,"featured_media":44703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[2290],"tags":[],"ppma_author":[2288],"class_list":["post-49220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglementations-cosmetique","author-christophe-brault-chevalier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e8glement Omnibus 2019 - Biorius<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l&#039;impact du r\u00e8glement Omnibus 2019 sur les cosm\u00e9tiques, y compris les nouvelles restrictions sur l&#039;acide salicylique et les mises \u00e0 jour sur les substances interdites.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e8glement Omnibus 2019 - Biorius\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;impact du r\u00e8glement Omnibus 2019 sur les cosm\u00e9tiques, y compris les nouvelles restrictions sur l&#039;acide salicylique et les mises \u00e0 jour sur les substances interdites.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/\" \/>\n<meta property=\"og:site_name\" content=\"Biorius\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-12T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T08:59:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1042\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christophe Brault-Chevalier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"nicolas.lenaers@biorius.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/\"},\"author\":{\"name\":\"nicolas.lenaers@biorius.com\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\"},\"headline\":\"R\u00e8glement Omnibus 2019\",\"datePublished\":\"2019-12-12T23:00:00+00:00\",\"dateModified\":\"2025-01-13T08:59:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/\"},\"wordCount\":1736,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"articleSection\":[\"R\u00e9glementations Cosm\u00e9tique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/\",\"url\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/\",\"name\":\"R\u00e8glement Omnibus 2019 - Biorius\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"datePublished\":\"2019-12-12T23:00:00+00:00\",\"dateModified\":\"2025-01-13T08:59:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\"},\"description\":\"D\u00e9couvrez l'impact du r\u00e8glement Omnibus 2019 sur les cosm\u00e9tiques, y compris les nouvelles restrictions sur l'acide salicylique et les mises \u00e0 jour sur les substances interdites.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"width\":1920,\"height\":1042,\"caption\":\"Discover how the 2019 Omnibus Regulation impacts cosmetics, including new restrictions on Salicylic Acid and updates on prohibited substances.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/le-reglement-omnibus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/biorius.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e8glement Omnibus 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/biorius.com\\\/fr\\\/\",\"name\":\"Biorius\",\"description\":\"You create dreams we protect them\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biorius.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\",\"name\":\"nicolas.lenaers@biorius.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=gf65cae9e2e07fb542ca434cf6ec306ac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g\",\"caption\":\"nicolas.lenaers@biorius.com\"},\"url\":\"https:\\\/\\\/biorius.com\\\/ko\\\/cosmetic-news\\\/author\\\/nicolas-lenaersbiorius-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e8glement Omnibus 2019 - Biorius","description":"D\u00e9couvrez l'impact du r\u00e8glement Omnibus 2019 sur les cosm\u00e9tiques, y compris les nouvelles restrictions sur l'acide salicylique et les mises \u00e0 jour sur les substances interdites.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e8glement Omnibus 2019 - Biorius","og_description":"D\u00e9couvrez l'impact du r\u00e8glement Omnibus 2019 sur les cosm\u00e9tiques, y compris les nouvelles restrictions sur l'acide salicylique et les mises \u00e0 jour sur les substances interdites.","og_url":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/","og_site_name":"Biorius","article_published_time":"2019-12-12T23:00:00+00:00","article_modified_time":"2025-01-13T08:59:55+00:00","og_image":[{"width":1920,"height":1042,"url":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","type":"image\/jpeg"}],"author":"Christophe Brault-Chevalier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"nicolas.lenaers@biorius.com","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#article","isPartOf":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/"},"author":{"name":"nicolas.lenaers@biorius.com","@id":"https:\/\/biorius.com\/fr\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3"},"headline":"R\u00e8glement Omnibus 2019","datePublished":"2019-12-12T23:00:00+00:00","dateModified":"2025-01-13T08:59:55+00:00","mainEntityOfPage":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/"},"wordCount":1736,"commentCount":0,"image":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#primaryimage"},"thumbnailUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","articleSection":["R\u00e9glementations Cosm\u00e9tique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/","url":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/","name":"R\u00e8glement Omnibus 2019 - Biorius","isPartOf":{"@id":"https:\/\/biorius.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#primaryimage"},"image":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#primaryimage"},"thumbnailUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","datePublished":"2019-12-12T23:00:00+00:00","dateModified":"2025-01-13T08:59:55+00:00","author":{"@id":"https:\/\/biorius.com\/fr\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3"},"description":"D\u00e9couvrez l'impact du r\u00e8glement Omnibus 2019 sur les cosm\u00e9tiques, y compris les nouvelles restrictions sur l'acide salicylique et les mises \u00e0 jour sur les substances interdites.","breadcrumb":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#primaryimage","url":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","contentUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","width":1920,"height":1042,"caption":"Discover how the 2019 Omnibus Regulation impacts cosmetics, including new restrictions on Salicylic Acid and updates on prohibited substances."},{"@type":"BreadcrumbList","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/le-reglement-omnibus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/biorius.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e8glement Omnibus 2019"}]},{"@type":"WebSite","@id":"https:\/\/biorius.com\/fr\/#website","url":"https:\/\/biorius.com\/fr\/","name":"Biorius","description":"You create dreams we protect them","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biorius.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/biorius.com\/fr\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3","name":"nicolas.lenaers@biorius.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=gf65cae9e2e07fb542ca434cf6ec306ac","url":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","caption":"nicolas.lenaers@biorius.com"},"url":"https:\/\/biorius.com\/ko\/cosmetic-news\/author\/nicolas-lenaersbiorius-com\/"}]}},"authors":[{"term_id":2288,"user_id":0,"is_guest":1,"slug":"christophe-brault-chevalier","display_name":"Christophe Brault-Chevalier","avatar_url":{"url":"https:\/\/biorius.com\/wp-content\/uploads\/2024\/08\/Christophe-Brault-Chevalier.webp","url2x":"https:\/\/biorius.com\/wp-content\/uploads\/2024\/08\/Christophe-Brault-Chevalier.webp"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/posts\/49220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/comments?post=49220"}],"version-history":[{"count":0,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/posts\/49220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/media\/44703"}],"wp:attachment":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/media?parent=49220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/categories?post=49220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/tags?post=49220"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/ppma_author?post=49220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}