{"id":48876,"date":"2018-01-18T00:00:00","date_gmt":"2018-01-17T23:00:00","guid":{"rendered":"https:\/\/biorius.com\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/"},"modified":"2024-05-08T11:24:31","modified_gmt":"2024-05-08T09:24:31","slug":"d4-et-d5-dans-les-produits-cosmetiques","status":"publish","type":"post","link":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/","title":{"rendered":"D4 et D5 dans les produits cosm\u00e9tiques"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Le r\u00e8glement limitant l&#8217;utilisation du D4 et du D5 dans les produits cosm\u00e9tiques lavables a \u00e9t\u00e9 publi\u00e9.<\/h2>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">18 janvier 2018<\/span><\/em><\/p>\n\n<p>BIORIUS vous a inform\u00e9 de l&#8217;\u00e9tat d&#8217;avancement du projet visant \u00e0 restreindre l&#8217;utilisation du Cyclopentasiloxane (D5) et du Cyclotetrasiloxane (D4) dans le cadre du r\u00e8glement REACH (CE n\u00b0 1907\/2006). Avec cette mise \u00e0 jour, BIORIUS vous informe que l&#8217;<strong><a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/PDF\/?uri=CELEX:32018R0035&amp;qid=1516260718056&amp;from=EN\">amendement<\/a><\/strong> correspondant <strong><a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/PDF\/?uri=CELEX:32018R0035&amp;qid=1516260718056&amp;from=EN\">(EU No 2018\/35)<\/a> \u00e0 l&#8217;annexe XVII du r\u00e8glement REACH a \u00e9t\u00e9 publi\u00e9 le 11 janvier 2018<\/strong>. Cette nouvelle l\u00e9gislation entrera en vigueur le 31 janvier 2018.<\/p>\n\n<p>Comme pr\u00e9vu, la restriction de l&#8217;utilisation du D5 et du D4 dans les produits cosm\u00e9tiques <span style=\"color: #93D500;\" class=\"ugb-highlight\"> lavables*<\/span> \u00e0 une concentration maximale de 0,1 % sera mise en \u0153uvre. En effet, les D4 et D5 pr\u00e9sentent un risque pour l&#8217;environnement et sont class\u00e9s comme substances tr\u00e8s persistantes et tr\u00e8s bioaccumulables (vPvB). En outre, le D4 est toxique et, comme indiqu\u00e9 dans l&#8217;IL-045, son utilisation dans les produits cosm\u00e9tiques sera interdite \u00e0 tr\u00e8s court terme.<\/p>\n\n<p>Comme pr\u00e9vu, une p\u00e9riode de transition de deux ans est accord\u00e9e pour permettre aux fabricants de cosm\u00e9tiques de mettre leurs produits en conformit\u00e9. Cela signifie que tous les produits cosm\u00e9tiques lavables sur le march\u00e9 de l&#8217;UE devront contenir moins de 0,1 % de D5 et moins de 0,1 % de D4 d&#8217;ici le 31 janvier 2020.<\/p>\n\n<p>Ce changement devrait avoir un impact important sur l&#8217;industrie cosm\u00e9tique. BIORIUS a observ\u00e9 que 5,5 % des produits lav\u00e9s de sa base de donn\u00e9es seront affect\u00e9s par cette restriction du projet. Votre CRM<strong>(Customer<\/strong> <strong>Relationship<\/strong> <strong>Manager<\/strong>) vous contactera spontan\u00e9ment au cas o\u00f9 certains de vos produits seraient affect\u00e9s.<\/p>\n\n<p>En outre, la Commission europ\u00e9enne a demand\u00e9 \u00e0 l&#8217;ECHA d&#8217;enqu\u00eater sur la n\u00e9cessit\u00e9 de restreindre l&#8217;utilisation du D4 et du D5 dans les produits cosm\u00e9tiques sans rin\u00e7age. Une proposition de restriction doit \u00eatre soumise le 13 avril 2018. \u00c0 partir de cette date, le processus r\u00e9glementaire peut durer environ deux ans, mais il est impossible de d\u00e9terminer aujourd&#8217;hui si cette \u00e9volution r\u00e9glementaire aboutira \u00e0 une restriction. Si c&#8217;est le cas, celle-ci pourrait \u00eatre appliqu\u00e9e dans environ deux ans et mise en \u0153uvre dans environ quatre ans.<\/p>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">*On entend par &#8220;produits cosm\u00e9tiques lavables&#8221; les produits cosm\u00e9tiques d\u00e9finis \u00e0 l&#8217;article 2, paragraphe 1, point a), du r\u00e8glement (CE) n\u00b0 1223\/2009 qui, dans des conditions normales d&#8217;utilisation, sont lav\u00e9s <strong>\u00e0 l&#8217;eau<\/strong> apr\u00e8s application.<\/span><\/em><\/p>\n\n<div class=\"wp-block-ugb-cta ugb-cta ugb-93439e6 ugb-cta ugb-cta--v2 ugb-cta--design-plain ugb-main-block\" id=\"\"><style>.ugb-93439e6 .ugb-button .ugb-button--inner{color:#93D500 !important}.ugb-93439e6 .ugb-button{border-color:#93D500 !important}.ugb-93439e6 .ugb-button:hover .ugb-button--inner{color:#93D500 !important}<\/style><div class=\"ugb-inner-block\"><div class=\"ugb-block-content\"><div class=\"ugb-cta__item\"><h3 class=\"ugb-cta__title\">Des questions ?<\/h3><div class=\"ugb-button-container\"><a class=\"ugb-button ugb-button--size-normal ugb-button--design-ghost\" href=\"https:\/\/biorius.com\/fr\/contact\/\" rel=\"\"><span class=\"ugb-button--inner\">Contactez nous<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n\n<h2 class=\"wp-block-heading\">Une interdiction du Cyclotetrasiloxane (D4) est attendue \u00e0 court terme<\/h2>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">6 juillet 2017<\/span><\/em><\/p>\n\n<p>La Commission europ\u00e9enne vient de soumettre cette proposition de r\u00e8glement \u00e0 l&#8217;Organisation mondiale du commerce (OMC), ce qui constitue l&#8217;une des derni\u00e8res \u00e9tapes \u00e0 franchir avant la publication d&#8217;un nouveau texte l\u00e9gislatif. Cette consultation au niveau de l&#8217;OMC a permis \u00e0 BIORIUS d&#8217;acc\u00e9der \u00e0 l&#8217;<a href=\"https:\/\/gallery.mailchimp.com\/d3d80b99002742cef41679506\/files\/6b0e23c1-dc38-4ddd-ad65-b3b5b91b96d4\/CMR_Omnibus_Regulation_WTO_level_Annex.pdf\">annexe de cette proposition de r\u00e8glement<\/a> et d&#8217;obtenir la liste exacte des ingr\u00e9dients concern\u00e9s.<\/p>\n\n<p>Outre les quelques ingr\u00e9dients d\u00e9j\u00e0 r\u00e9glement\u00e9s qui changeront de statut, nous avons appris qu&#8217;environ 200 autres substances seront interdites en m\u00eame temps. La grande majorit\u00e9 de ces substances ne sont pas utilis\u00e9es dans les produits cosm\u00e9tiques et sont simplement ajout\u00e9es par souci de coh\u00e9rence avec le r\u00e8glement CLP (CE n\u00b0 1272\/2008). Toutefois, il existe une exception \u00e0 la r\u00e8gle et nous avons observ\u00e9 que le cyclotetrasiloxane (D4, CAS 556-67-2) avait \u00e9galement \u00e9t\u00e9 inclus dans cette liste.<\/p>\n\n<p>Comme indiqu\u00e9 ci-dessous, le cyclotetrasiloxane a \u00e9galement suscit\u00e9 des pr\u00e9occupations environnementales et nous nous attendons \u00e0 ce que cet ingr\u00e9dient soit limit\u00e9 \u00e0 un maximum de 0,1 % dans les prochaines ann\u00e9es (d&#8217;abord dans les produits lavables et ensuite, tr\u00e8s probablement, dans les produits non rinc\u00e9s). Sur la base des informations re\u00e7ues aujourd&#8217;hui, il semble que l&#8217;utilisation du cyclotetrasiloxane dans les cosm\u00e9tiques sera interdite bien avant.<\/p>\n\n<p>La p\u00e9riode de consultation au niveau de l&#8217;OMC se terminera le 27 ao\u00fbt 2017. Bien que cela ne puisse \u00eatre totalement exclu, il est rare qu&#8217;une proposition de r\u00e8glement soit bloqu\u00e9e \u00e0 ce stade. Par exp\u00e9rience, BIORIUS sait qu&#8217;il faut ensuite environ 5 mois pour finaliser le texte juridique et le publier au Journal officiel de l&#8217;UE. Le r\u00e8glement entre en vigueur 20 jours apr\u00e8s sa publication. Cela signifie que les <strong>produits contenant du D4 comme ingr\u00e9dient devront probablement \u00eatre retir\u00e9s du march\u00e9 d&#8217;ici la mi-f\u00e9vrier 2018<\/strong>. Comme le pr\u00e9voit l&#8217;article 17, les traces de D4 pr\u00e9sentes dans les produits cosm\u00e9tiques en tant qu&#8217;impuret\u00e9 resteront tol\u00e9r\u00e9es.<\/p>\n\n<h2 class=\"wp-block-heading\">Mise \u00e0 jour importante sur le D4 et le D5<\/h2>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">23 f\u00e9vrier 2017<\/span><\/em><\/p>\n\n<p>Comme vous le savez peut-\u00eatre, un projet de restriction du Cyclopentasiloxane (D5) et du Cyclotetrasiloxane (D4) a \u00e9t\u00e9 initi\u00e9 en 2015 et vise \u00e0 limiter \u00e0 0,1% l&#8217;utilisation de ces deux ingr\u00e9dients dans les produits de lavage.<sup>\n  <span style=\"color: #93D500;\" class=\"ugb-highlight\">*<\/span>\n<\/sup> les produits cosm\u00e9tiques lavables. Ces limitations ne sont pas li\u00e9es au r\u00e8glement de l&#8217;UE sur les cosm\u00e9tiques (qui traite des questions de s\u00e9curit\u00e9 des consommateurs), mais r\u00e9pondent \u00e0 des pr\u00e9occupations environnementales dans le cadre du r\u00e8glement REACH (CE n\u00b0 1907\/2006).<\/p>\n\n<p>BIORIUS confirme qu&#8217;il est tr\u00e8s probable que ces restrictions soient mises en \u0153uvre, \u00e9tant donn\u00e9 que l&#8217;OMC a \u00e9t\u00e9 inform\u00e9e de cette <a href=\"https:\/\/ec.europa.eu\/growth\/tools-databases\/tbt\/en\/search\/?tbtaction=get.project&amp;Country_ID=EU&amp;num=456&amp;dspLang=en&amp;basdatedeb=&amp;basdatefin=&amp;baspays=EU&amp;baspays2=EU&amp;basnotifnum=&amp;basnotifnum2=&amp;bastypepays=CE&amp;baskeywords=cyclopentasiloxane&amp;project_type_num=1&amp;project_type_id=1&amp;lang_id=EN\">proposition de r\u00e9glementation<\/a> (et de son <a href=\"https:\/\/ec.europa.eu\/growth\/tools-databases\/tbt\/en\/search\/?tbtaction=get.project&amp;Country_ID=EU&amp;num=456&amp;dspLang=en&amp;basdatedeb=&amp;basdatefin=&amp;baspays=EU&amp;baspays2=EU&amp;basnotifnum=&amp;basnotifnum2=&amp;bastypepays=CE&amp;baskeywords=cyclopentasiloxane&amp;project_type_num=2&amp;project_type_id=1&amp;lang_id=EN\">annexe<\/a>). La notification \u00e0 l&#8217;OMC est g\u00e9n\u00e9ralement la toute derni\u00e8re \u00e9tape de l&#8217;\u00e9laboration d&#8217;une r\u00e9glementation et les projets l\u00e9gislatifs sont rarement interrompus \u00e0 ce stade. Comme estim\u00e9 dans l&#8217;IL-015, la modification de l&#8217;annexe XVII du r\u00e8glement REACH sera probablement publi\u00e9e en septembre 2017. Une p\u00e9riode de transition de deux ans d\u00e9butera ensuite, ce qui signifie que tous les produits cosm\u00e9tiques lavables sur le march\u00e9 de l&#8217;UE devront contenir moins de 0,1 % de D5 et moins de 0,1 % de D4 d&#8217;ici septembre 2019.<\/p>\n\n<p>Ce changement devrait avoir un impact important sur l&#8217;industrie cosm\u00e9tique. BIORIUS a observ\u00e9 que 5,5 % des produits lav\u00e9s de sa base de donn\u00e9es seront affect\u00e9s par cette restriction du projet. Votre CRM<strong>(Customer<\/strong> <strong>Relationship<\/strong> <strong>Manager<\/strong>) vous contactera spontan\u00e9ment au cas o\u00f9 certains de vos produits seraient affect\u00e9s.<\/p>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">*Le r\u00e8glement europ\u00e9en sur les cosm\u00e9tiques utilise le terme &#8220;rin\u00e7age&#8221; pour les produits qui sont \u00e9limin\u00e9s par lavage, mais aussi pour les produits qui sont \u00e9limin\u00e9s par essuyage, tels que les lingettes pour b\u00e9b\u00e9s. Les produits d&#8217;essuyage n&#8217;entra\u00eenant normalement pas d&#8217;\u00e9missions aquatiques, il n&#8217;a pas \u00e9t\u00e9 jug\u00e9 appropri\u00e9 de les inclure dans la restriction ; c&#8217;est pourquoi le terme &#8220;lavage&#8221; a \u00e9t\u00e9 utilis\u00e9.<\/span><\/em><\/p>\n\n<h2 class=\"wp-block-heading\">Mise \u00e0 jour sur les D4 et D5<\/h2>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\"><sup>2<\/sup> septembre 2016<\/span><\/em><\/p>\n\n<h3 class=\"wp-block-heading\"><strong>L&#8217;avis du CSSC<\/strong><\/h3>\n\n<p>Le 25 mars 2015, le CSSC a publi\u00e9 un projet d&#8217;avis scientifique concluant que l&#8217;utilisation du D5 dans les produits cosm\u00e9tiques est sans danger <strong>, sauf<\/strong>:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Lorsqu&#8217;ils sont utilis\u00e9s dans des <strong>lotions corporelles<\/strong> et des formulations de coiffage et dans les formes de produits qui peuvent donner lieu \u00e0 une exposition pulmonaire du consommateur par inhalation, par exemple les a\u00e9rosols, les sprays pressuris\u00e9s, les poudres, etc.<\/li>\n\n\n\n<li>Lorsqu&#8217;il <strong>contient plus de 1 % de D4<\/strong> (Cyclotetrasiloxane), qui est class\u00e9 comme substance reprotoxique dans l&#8217;UE.<\/li>\n<\/ul>\n\n<p>Ces conclusions ont \u00e9t\u00e9 soumises \u00e0 une consultation publique et l&#8217;industrie cosm\u00e9tique a vivement r\u00e9agi. En cons\u00e9quence, et sur la base de donn\u00e9es de s\u00e9curit\u00e9 suppl\u00e9mentaires, le CSSC a r\u00e9vis\u00e9 son avis scientifique. La version finale a \u00e9t\u00e9 adopt\u00e9e le 29 juillet et publi\u00e9e quelques jours plus tard sur le site web du SCCS<a href=\"https:\/\/ec.europa.eu\/health\/scientific_committees\/consumer_safety\/docs\/sccs_o_174.pdf\">(SCCS\/1549\/15)<\/a>. Elle conclut maintenant que l&#8217;utilisation du D5 dans les produits cosm\u00e9tiques est sans danger <strong>, sauf<\/strong>.. :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Utilis\u00e9 dans les a\u00e9rosols de coiffure et les produits de protection solaire.<\/li>\n\n\n\n<li>Lorsque le niveau de D4 est &#8220;trop \u00e9lev\u00e9&#8221;. Par cons\u00e9quent, le niveau d&#8217;impuret\u00e9 du D4 en tant qu&#8217;impuret\u00e9 du cyclopentasiloxane (D5) <strong>doit \u00eatre maintenu aussi bas<\/strong> que possible.<\/li>\n<\/ul>\n\n<p>La r\u00e9vision de cet avis est une bonne nouvelle car elle maintient l&#8217;utilisation du D5 dans les lotions corporelles. En outre, l&#8217;avis final est moins strict en ce qui concerne le niveau tol\u00e9r\u00e9 de D4 en tant qu&#8217;impuret\u00e9 de D5, ce qui laisse un peu plus de souplesse pour la gestion de ces traces.<\/p>\n\n<p>Cet avis doit \u00eatre transpos\u00e9 dans la l\u00e9gislation, ce qui prend toujours beaucoup de temps. Il serait sp\u00e9culatif de proposer une date pour la publication d&#8217;un amendement au r\u00e8glement sur les cosm\u00e9tiques. Cependant, deux \u00e0 trois ans est le d\u00e9lai moyen n\u00e9cessaire pour une telle \u00e9volution r\u00e9glementaire.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>La restriction de l&#8217;ECHA<\/strong><\/h3>\n\n<p>Le 11 mars 2016, le comit\u00e9 d&#8217;\u00e9valuation des risques (RAC) et le comit\u00e9 d&#8217;analyse socio-\u00e9conomique (SEAC) de l&#8217;ECHA ont publi\u00e9 un rapport conjoint dans lequel ils conviennent que la proposition de restriction du D4 et du D5 \u00e0 0,1 % dans les produits lavables soumise par le Royaume-Uni est appropri\u00e9e (les produits non rinc\u00e9s et les lingettes sont hors du champ d&#8217;application de ce d\u00e9veloppement).<\/p>\n\n<p>Une consultation publique a eu lieu et l&#8217;industrie cosm\u00e9tique a soumis de nombreux commentaires contre cette \u00e9volution r\u00e9glementaire. Sur cette base, le CCR et le CCED ont apport\u00e9 quelques modifications et clarifications \u00e0 la justification de leur avis conjoint, mais <a href=\"https:\/\/echa.europa.eu\/documents\/10162\/23ca076a-9cd8-4baf-8b76-15a0b71ad869\">l&#8217;ont adopt\u00e9<\/a> \u00e0 la mi-juin sans modification. En outre, le RAC et le SEAC ont confirm\u00e9 leur point de vue selon lequel la restriction de l&#8217;utilisation du D4 et du D5 dans les produits de soins personnels &#8220;lavables&#8221; devrait entrer en vigueur deux ans apr\u00e8s la publication au journal officiel. Il est tr\u00e8s probable que cette <strong>restriction du D4 et du D5 \u00e0 0,1 % dans les produits lavables<\/strong> sera mise en \u0153uvre.<\/p>\n\n<p>Les deux avis des comit\u00e9s de l&#8217;ECHA1 contribuent \u00e0 la d\u00e9cision de la Commission europ\u00e9enne, qui adopte alors un point de vue \u00e9quilibr\u00e9 sur les risques identifi\u00e9s et sur les avantages et les co\u00fbts de la restriction propos\u00e9e. Dans les trois mois suivant la r\u00e9ception des avis des deux comit\u00e9s, la Commission fournira un projet de modification de la liste des restrictions figurant \u00e0 l&#8217;annexe XVII de REACH. La d\u00e9cision finale est prise dans le cadre d&#8217;une proc\u00e9dure de comitologie avec contr\u00f4le impliquant les \u00c9tats membres et le Parlement europ\u00e9en. La proc\u00e9dure compl\u00e8te prend g\u00e9n\u00e9ralement un \u00e0 deux ans avant la publication d&#8217;une modification du r\u00e8glement REACH. Ensuite, et comme l&#8217;ont propos\u00e9 le CCR et le CASE, la p\u00e9riode de transition pour la mise en \u0153uvre de cette restriction une fois la l\u00e9gislation modifi\u00e9e devrait \u00eatre de deux ans.<\/p>\n\n<h2 class=\"wp-block-heading\">Un pas de plus vers la restriction du D4 et du D5 dans les produits \u00e0 rincer<\/h2>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">1er avril 2016<\/span><\/em><\/p>\n\n<p>Dans l&#8217;article ci-dessous, BIORIUS vous informe des d\u00e9veloppements r\u00e9glementaires en cours qui menacent le D4 (Cyclotetrasiloxane) et le D5 (Cyclopentasiloxane) lorsqu&#8217;ils sont utilis\u00e9s dans des produits \u00e0 rincer. Il est important de rappeler que ce dossier n&#8217;est pas g\u00e9r\u00e9 par l&#8217;unit\u00e9 &#8220;Cosm\u00e9tiques&#8221; de la Commission europ\u00e9enne mais par l&#8217;ECHA, l&#8217;Agence europ\u00e9enne des produits chimiques. La proposition de restriction est motiv\u00e9e par des pr\u00e9occupations environnementales et non par des questions de s\u00e9curit\u00e9 humaine.<\/p>\n\n<p>Le 11 mars 2016, le comit\u00e9 d&#8217;\u00e9valuation des risques (RAC) et le comit\u00e9 d&#8217;analyse socio-\u00e9conomique (SEAC) de l&#8217;ECHA ont <a href=\"https:\/\/echa.europa.eu\/documents\/10162\/23cd6eda-688d-44ea-99b0-a254a8f83ba5\">publi\u00e9 un rapport conjoint<\/a> dans lequel ils conviennent que la proposition de restriction du D4 et du D5 \u00e0 0,1 % dans les produits \u00e0 rincer soumise par le Royaume-Uni est appropri\u00e9e. \u00c0 ce stade, les produits sans rin\u00e7age n&#8217;entrent pas dans le cadre de ce d\u00e9veloppement.<\/p>\n\n<p>La prochaine \u00e9tape de ce processus r\u00e9glementaire est la consultation publique sur le projet d&#8217;avis du CCED et toutes les parties int\u00e9ress\u00e9es sont libres de soumettre leurs commentaires. La date limite pour participer \u00e0 cette consultation publique est le 16 mai 2016.<\/p>\n\n<p>Il est encore trop t\u00f4t pour d\u00e9terminer l&#8217;issue de cette \u00e9volution r\u00e9glementaire, mais BIORIUS estime que la probabilit\u00e9 de voir ces ingr\u00e9dients restreints dans les cat\u00e9gories D4 et D5 est \u00e9lev\u00e9e. Nous continuerons \u00e0 vous informer sur ce dossier, mais vous pouvez \u00e9galement <a href=\"https:\/\/echa.europa.eu\/restrictions-under-consideration\/-\/substance-rev\/9444\/term\">suivre le processus r\u00e9glementaire<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\">D\u00e9veloppements r\u00e9glementaires en cours sur D4 et D5<\/h2>\n\n<p><em><span style=\"color: #93D500;\" class=\"ugb-highlight\">15 juillet 2015<\/span><\/em><\/p>\n\n<p>Avec cette premi\u00e8re lettre d&#8217;information, Biorius souhaite vous informer des d\u00e9veloppements r\u00e9glementaires actuels concernant deux ingr\u00e9dients largement utilis\u00e9s dans l&#8217;industrie cosm\u00e9tique pour leurs propri\u00e9t\u00e9s de conditionnement de la peau et des cheveux : Cyclopentasiloxane, \u00e9galement appel\u00e9 <sup>D51<\/sup>, et Cyclotetrasiloxane, \u00e9galement appel\u00e9 <sup>D42<\/sup>. En effet, ces ingr\u00e9dients sont dans le collimateur de l&#8217;ECHA <sup>RAC3<\/sup> et du <sup>SCCS4<\/sup>, deux institutions importantes au centre des processus r\u00e9glementaires affectant la gestion des ingr\u00e9dients cosm\u00e9tiques en Europe.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>L&#8217;avis du CSSC<\/strong><\/h3>\n\n<p>Le 25 mars 2015, le CSSC a publi\u00e9 un avis scientifique sur le D5<a href=\"https:\/\/ec.europa.eu\/health\/scientific_committees\/consumer_safety\/docs\/sccs_o_174.pdf\">(SCCS\/1549\/15)<\/a> bas\u00e9 sur un rapport de s\u00e9curit\u00e9 soumis par l&#8217;association commerciale &#8220;Cosmetics Europe&#8221;. Apr\u00e8s \u00e9valuation du rapport, le CSSC a conclu que l&#8217;utilisation du D5 dans les produits cosm\u00e9tiques est sans danger, sauf dans les lotions corporelles et les produits coiffants et dans les formes de produits qui peuvent donner lieu \u00e0 une exposition pulmonaire du consommateur par inhalation, par exemple les a\u00e9rosols, les vaporisateurs sous pression, les poudres, etc. Par ailleurs, le CSSC a rappel\u00e9 que le D4 est class\u00e9 comme substance reprotoxique en Europe et a recommand\u00e9 que le niveau de puret\u00e9 du D5 dans les produits cosm\u00e9tiques mis sur le march\u00e9 soit sup\u00e9rieur \u00e0 99% (c&#8217;est-\u00e0-dire avec moins de 1% de cyclotetrasiloxane).<\/p>\n\n<p>1 CAS 541-02-6, EINECS 208-764-9, \u00e9galement appel\u00e9 d\u00e9cam\u00e9thylcyclopentasiloxane<br\/>2 CAS 556-67-2 \/ 293-51-6, EINECS 209-136-7, \u00e9galement appel\u00e9 Octam\u00e9thylcyclot\u00e9trasiloxane<br\/>3 Comit\u00e9 d&#8217;\u00e9valuation des risques de l&#8217;Agence europ\u00e9enne des produits chimiques.<br\/>4 Comit\u00e9 scientifique pour la s\u00e9curit\u00e9 des consommateurs.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>L&#8217;\u00e9valuation du CCR de l&#8217;ECHA<\/strong><\/h3>\n\n<p>Le 17 avril 2015, le Royaume-Uni a soumis \u00e0 l&#8217;ECHA une <a href=\"https:\/\/echa.europa.eu\/documents\/10162\/12e03ccd-7c84-4325-bde1-9daeb562a6be\">proposition de restriction<\/a> concernant le D4 et le D5. Cette proposition est motiv\u00e9e par des pr\u00e9occupations environnementales (ces ingr\u00e9dients se sont r\u00e9v\u00e9l\u00e9s tr\u00e8s persistants et tr\u00e8s bioaccumulables) et vise \u00e0 limiter l&#8217;utilisation du D4 et du D5 \u00e0 un maximum de 0,1 % dans tous les produits cosm\u00e9tiques \u00e0 rincer.<br\/>La consultation publique sur cette proposition de restriction a d\u00e9but\u00e9 le 18 juin 2015 et l&#8217;industrie cosm\u00e9tique est invit\u00e9e \u00e0 formuler des commentaires scientifiques sur le dossier de restriction, mais aussi \u00e0 pr\u00e9senter des arguments socio-\u00e9conomiques. La date limite de soumission des commentaires est le 18 d\u00e9cembre 2015 et l&#8217;\u00e9valuation du comit\u00e9 d&#8217;\u00e9valuation des risques de l&#8217;ECHA commencera juste apr\u00e8s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e8glement limitant l&#8217;utilisation du D4 et du D5 dans les produits cosm\u00e9tiques lavables a \u00e9t\u00e9 publi\u00e9. 18 janvier 2018 BIORIUS vous a inform\u00e9 de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":44703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[2289,2290],"tags":[],"ppma_author":[],"class_list":["post-48876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosmetic-regulations","category-reglementations-cosmetique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D4 et D5 dans les produits cosm\u00e9tiques - Biorius<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D4 et D5 dans les produits cosm\u00e9tiques - Biorius\" \/>\n<meta property=\"og:description\" content=\"Le r\u00e8glement limitant l&#8217;utilisation du D4 et du D5 dans les produits cosm\u00e9tiques lavables a \u00e9t\u00e9 publi\u00e9. 18 janvier 2018 BIORIUS vous a inform\u00e9 de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Biorius\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-17T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T09:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1042\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nicolas.lenaers@biorius.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"nicolas.lenaers@biorius.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/\"},\"author\":{\"name\":\"nicolas.lenaers@biorius.com\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\"},\"headline\":\"D4 et D5 dans les produits cosm\u00e9tiques\",\"datePublished\":\"2018-01-17T23:00:00+00:00\",\"dateModified\":\"2024-05-08T09:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/\"},\"wordCount\":2495,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"articleSection\":[\"Cosmetic Regulations\",\"R\u00e9glementations Cosm\u00e9tique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/\",\"url\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/\",\"name\":\"D4 et D5 dans les produits cosm\u00e9tiques - Biorius\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"datePublished\":\"2018-01-17T23:00:00+00:00\",\"dateModified\":\"2024-05-08T09:24:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/biorius.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/books-1845614_1920.jpg\",\"width\":1920,\"height\":1042,\"caption\":\"Discover how the 2019 Omnibus Regulation impacts cosmetics, including new restrictions on Salicylic Acid and updates on prohibited substances.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/cosmetic-news\\\/d4-et-d5-dans-les-produits-cosmetiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/biorius.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D4 et D5 dans les produits cosm\u00e9tiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/biorius.com\\\/fr\\\/\",\"name\":\"Biorius\",\"description\":\"You create dreams we protect them\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biorius.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biorius.com\\\/fr\\\/#\\\/schema\\\/person\\\/118636d0af6db915f51e7a434d16faa3\",\"name\":\"nicolas.lenaers@biorius.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=gf65cae9e2e07fb542ca434cf6ec306ac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g\",\"caption\":\"nicolas.lenaers@biorius.com\"},\"url\":\"https:\\\/\\\/biorius.com\\\/ja\\\/cosmetic-news\\\/author\\\/nicolas-lenaersbiorius-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D4 et D5 dans les produits cosm\u00e9tiques - Biorius","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/","og_locale":"fr_FR","og_type":"article","og_title":"D4 et D5 dans les produits cosm\u00e9tiques - Biorius","og_description":"Le r\u00e8glement limitant l&#8217;utilisation du D4 et du D5 dans les produits cosm\u00e9tiques lavables a \u00e9t\u00e9 publi\u00e9. 18 janvier 2018 BIORIUS vous a inform\u00e9 de...","og_url":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/","og_site_name":"Biorius","article_published_time":"2018-01-17T23:00:00+00:00","article_modified_time":"2024-05-08T09:24:31+00:00","og_image":[{"width":1920,"height":1042,"url":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","type":"image\/jpeg"}],"author":"nicolas.lenaers@biorius.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"nicolas.lenaers@biorius.com","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#article","isPartOf":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/"},"author":{"name":"nicolas.lenaers@biorius.com","@id":"https:\/\/biorius.com\/fr\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3"},"headline":"D4 et D5 dans les produits cosm\u00e9tiques","datePublished":"2018-01-17T23:00:00+00:00","dateModified":"2024-05-08T09:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/"},"wordCount":2495,"commentCount":0,"image":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#primaryimage"},"thumbnailUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","articleSection":["Cosmetic Regulations","R\u00e9glementations Cosm\u00e9tique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/","url":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/","name":"D4 et D5 dans les produits cosm\u00e9tiques - Biorius","isPartOf":{"@id":"https:\/\/biorius.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#primaryimage"},"image":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#primaryimage"},"thumbnailUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","datePublished":"2018-01-17T23:00:00+00:00","dateModified":"2024-05-08T09:24:31+00:00","author":{"@id":"https:\/\/biorius.com\/fr\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3"},"breadcrumb":{"@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#primaryimage","url":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","contentUrl":"https:\/\/biorius.com\/wp-content\/uploads\/2023\/10\/books-1845614_1920.jpg","width":1920,"height":1042,"caption":"Discover how the 2019 Omnibus Regulation impacts cosmetics, including new restrictions on Salicylic Acid and updates on prohibited substances."},{"@type":"BreadcrumbList","@id":"https:\/\/biorius.com\/fr\/cosmetic-news\/d4-et-d5-dans-les-produits-cosmetiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/biorius.com\/fr\/"},{"@type":"ListItem","position":2,"name":"D4 et D5 dans les produits cosm\u00e9tiques"}]},{"@type":"WebSite","@id":"https:\/\/biorius.com\/fr\/#website","url":"https:\/\/biorius.com\/fr\/","name":"Biorius","description":"You create dreams we protect them","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biorius.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/biorius.com\/fr\/#\/schema\/person\/118636d0af6db915f51e7a434d16faa3","name":"nicolas.lenaers@biorius.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=gf65cae9e2e07fb542ca434cf6ec306ac","url":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","caption":"nicolas.lenaers@biorius.com"},"url":"https:\/\/biorius.com\/ja\/cosmetic-news\/author\/nicolas-lenaersbiorius-com\/"}]}},"authors":[{"term_id":2594,"user_id":2,"is_guest":0,"slug":"nicolas-lenaersbiorius-com","display_name":"nicolas.lenaers@biorius.com","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/7450c58c275f611cb86faf5b3b4ac4f1690203c164517e77349b33518fcd563c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/posts\/48876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/comments?post=48876"}],"version-history":[{"count":0,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/posts\/48876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/media\/44703"}],"wp:attachment":[{"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/media?parent=48876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/categories?post=48876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/tags?post=48876"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/biorius.com\/fr\/wp-json\/wp\/v2\/ppma_author?post=48876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}